{"id":19913,"date":"2024-11-20T10:23:58","date_gmt":"2024-11-20T15:23:58","guid":{"rendered":"https:\/\/canadiansciencecentres.ca\/?p=19913"},"modified":"2024-11-20T10:26:49","modified_gmt":"2024-11-20T15:26:49","slug":"linstitut-royal-canadien-des-sciences-souligne-son-175e-anniversaire-en-honorant-les-defenseurs-des-sciences-a-travers-le-canada","status":"publish","type":"post","link":"https:\/\/canadiansciencecentres.ca\/fr\/actualites\/linstitut-royal-canadien-des-sciences-souligne-son-175e-anniversaire-en-honorant-les-defenseurs-des-sciences-a-travers-le-canada\/","title":{"rendered":"l&rsquo;Institut royal canadien des sciences souligne son 175e anniversaire en honorant les d\u00e9fenseurs des sciences \u00e0 travers le Canada"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c0 l&rsquo;occasion de son 175e anniversaire, l\u2019Institut royal canadien des sciences (IRCS) c\u00e9l\u00e8bre l&rsquo;engagement scientifique en d\u00e9cernant la m\u00e9daille Sandford Fleming 2024 pour l&rsquo;excellence en communication scientifique \u00e0 l&rsquo;\u00e9crivaine scientifique ind\u00e9pendante Alanna Mitchell, et le prix William Edmond Logan \u00e0 l&rsquo;Association canadienne des centres de sciences (ACCS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un ajout sp\u00e9cial aux prix de cette ann\u00e9e, une s\u00e9lection d&rsquo;\u00e9minents Canadiens seront honor\u00e9s par des m\u00e9dailles du couronnement du roi Charles III. Parmi les r\u00e9cipiendaires figurent l\u2019\u00e9ducateur Timothy Caulfield, l&rsquo;influenceuse scientifique Samantha Yammine (ScienceSam), les stars de YouTube AsapScience et les animateurs de l&rsquo;\u00e9mission The Nature of Things de la CBC, Sarika Cullis-Suzuki et Anthony Morgan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis 175 ans, IRCS met les Canadiens en contact avec la science afin de favoriser le dialogue, la d\u00e9couverte et la communaut\u00e9, et de cr\u00e9er une culture scientifique attrayante pour tous. L&rsquo;organisme de bienfaisance d\u00e9cerne chaque ann\u00e9e la m\u00e9daille et la citation Sandford Fleming \u00e0 un Canadien.ne qui a contribu\u00e9 de mani\u00e8re exceptionnelle \u00e0 la compr\u00e9hension de la science par le public. Parmi les pr\u00e9c\u00e9dents laur\u00e9ats figurent David Suzuki, Ursula Franklin, Chris Hadfield et Andr\u00e9 Picard.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le prix William Edmond Logan r\u00e9compense des organisations plut\u00f4t que des individus. Parmi les anciens laur\u00e9ats figurent Celestica, IBM Canada, SciXchange de l&rsquo;universit\u00e9 m\u00e9tropolitaine de Toronto et Quirks and Quarks de la radio de la CBC. Ensemble, la m\u00e9daille Fleming et le prix Logan occupent un cr\u00e9neau essentiel dans la c\u00e9l\u00e9bration des efforts exceptionnels de communication scientifique au Canada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tant qu&rsquo;organisme \u00e0 charte royale, IRCS a \u00e9t\u00e9 choisi pour honorer un certain nombre de Canadien.ne.s distingu\u00e9s en leur remettant la m\u00e9daille du couronnement du roi Charles III pour leur contribution importante au Canada et \u00e0 leur communaut\u00e9. L&rsquo;Institut d\u00e9cernera des m\u00e9dailles \u00e0 ceux dont le travail contribue \u00e0 la mission de l&rsquo;organisme de bienfaisance, qui est de promouvoir la culture scientifique au Canada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carrie Boyce, directrice g\u00e9n\u00e9rale de IRCS, d\u00e9clare : \u00ab C&rsquo;est un grand honneur de reconna\u00eetre les laur\u00e9ats de cette ann\u00e9e. Ces partenaires influents travaillent avec enthousiasme \u00e0 l&rsquo;avancement de la communaut\u00e9 scientifique pour tous les Canadiens et Canadiennes, en faisant conna\u00eetre \u00e0 des millions de personnes chaque ann\u00e9e la valeur de la connaissance et de l&rsquo;int\u00e9grit\u00e9 scientifiques. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 propos des prix, Alanna Mitchell remarque : \u00ab Nous vivons une \u00e9poque o\u00f9 les fondements m\u00eames de la science et de la v\u00e9rit\u00e9 sont attaqu\u00e9s \u00e0 l&rsquo;\u00e9chelle mondiale. La propagande, le doute et la d\u00e9sinformation se sont install\u00e9s dans le discours public \u00e0 un degr\u00e9 que je trouve alarmant. Recevoir ce prix, cette ann\u00e9e, est donc une douce validation du fait que la t\u00e2che de d\u00e9mocratiser la science est importante et que nous devons continuer \u00e0 la mener \u00e0 bien !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Tout au long de son illustre carri\u00e8re, Alanna a eu un impact consid\u00e9rable sur le reportage scientifique et l&rsquo;application des connaissances au Canada et au-del\u00e0 \u00bb, a d\u00e9clar\u00e9 Carrie Boyce.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;Association canadienne des centres de sciences (ACCS) est le plus grand r\u00e9seau d&rsquo;organisations d&rsquo;engagement scientifique au Canada. Ses membres comprennent des centres de sciences, des mus\u00e9es, des zoos, des aquariums et des organisations d&rsquo;apprentissage informel des STIM de premier plan d&rsquo;un oc\u00e9an \u00e0 l&rsquo;autre. Les membres de l&rsquo;ACCS rejoignent collectivement plus de 10 millions de personnes issues de publics multig\u00e9n\u00e9rationnels chaque ann\u00e9e.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab L&rsquo;ACCS est ravie d&rsquo;accepter le prix William Edmond Logan de cette ann\u00e9e. Notre conseil d&rsquo;administration, notre \u00e9quipe d&#8217;employ\u00e9s et de b\u00e9n\u00e9voles d\u00e9vou\u00e9s, et notre r\u00e9seau dans son ensemble travaillent dur pour faire progresser la culture de la science et de l&rsquo;innovation au Canada. C&rsquo;est un v\u00e9ritable honneur que d&rsquo;\u00eatre reconnu pour ce travail acharn\u00e9 et pour l&rsquo;impact que nous avons sur la vie des gens au Canada et dans le monde entier. Nous consid\u00e9rons ce moment comme un marqueur de grand succ\u00e8s, et nous l&rsquo;utiliserons pour nous propulser vers l&rsquo;avant alors que nous continuons \u00e0 d\u00e9fendre ce secteur vital de notre soci\u00e9t\u00e9. \u00bb\u00a0<\/p><cite>Marianne Mader, directrice g\u00e9n\u00e9rale de l&rsquo;ACCS<\/cite><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Jock Fleming, pr\u00e9sident de IRCS et arri\u00e8re-arri\u00e8re-petit-fils du fondateur de l&rsquo;Institut, Sir Sandford Fleming, qui a donn\u00e9 son nom \u00e0 la m\u00e9daille Fleming, s&rsquo;exprime sur la victoire de l&rsquo;ACCS : \u00ab Nos missions collectives se chevauchent souvent et c&rsquo;est toujours un plaisir de travailler en partenariat avec les centres scientifiques locaux, les mus\u00e9es, les aquariums et autres, sans oublier LaSciencedAbord, dans la lutte contre la d\u00e9sinformation. Le comit\u00e9 des prix a d\u00e9cid\u00e9 \u00e0 l&rsquo;unanimit\u00e9 de reconna\u00eetre l&rsquo;\u00e9norme contribution de l&rsquo;ACCS \u00e0 la communication scientifique au Canada et ailleurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une c\u00e9r\u00e9monie priv\u00e9e pour c\u00e9l\u00e9brer toutes les contributions des laur\u00e9ats au paysage scientifique canadien se tiendra au Zoo de Toronto (une organisation membre de l&rsquo;ACCS) le 4 d\u00e9cembre, parrain\u00e9e par la Burgundy Asset Management Ltd.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;* * * * *<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos de l\u2019Institut royal canadien des sciences&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">l\u2019Institut royal canadien des sciences est la plus ancienne organisation scientifique du Canada, fond\u00e9e en 1849. C\u00e9l\u00e9brant son 175e anniversaire, l\u2019Institut royal canadien des sciences est un organisme de bienfaisance enregistr\u00e9 dont la programme prim\u00e9 construit la culture scientifique au Canada, en fournissant une plateforme pour l&rsquo;engagement des adultes avec les scientifiques afin de favoriser la pens\u00e9e critique, d&rsquo;\u00e9largir le dialogue scientifique et de promouvoir une prise de d\u00e9cision \u00e9clair\u00e9e. L&rsquo;Institut forme \u00e9galement les scientifiques \u00e0 devenir de meilleurs communicateurs, afin qu&rsquo;ils communiquent leurs recherches de pointe au public de mani\u00e8re cr\u00e9ative, inspirante et stimulante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contact<\/strong>: Carrie Boyce, Directrice g\u00e9n\u00e9rale, l\u2019Institut royal canadien des sciences&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Courriel: cboyce@rciscience.ca; Tel: +1 416 977 2983<a href=\"http:\/\/www.rciscience.ca\/\">www.rciscience.ca<\/a> &nbsp; | &nbsp; <a href=\"https:\/\/drive.google.com\/drive\/folders\/1IV6hhoZWm3w7HC-HH_UQL4Ab7WE1QStL?usp=sharing\">Kit de presse<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ACCS est ravie d&rsquo;accepter le prix William Edmond Logan de cette ann\u00e9e. Notre conseil d&rsquo;administration, notre \u00e9quipe d&#8217;employ\u00e9s et de b\u00e9n\u00e9voles d\u00e9vou\u00e9s, et notre r\u00e9seau dans son ensemble travaillent dur pour faire progresser la culture de la science et de l&rsquo;innovation au Canada. C&rsquo;est un v\u00e9ritable honneur que d&rsquo;\u00eatre reconnu pour ce travail acharn\u00e9 et pour l&rsquo;impact que nous avons sur la vie des gens au Canada et dans le monde entier. Nous consid\u00e9rons ce moment comme un marqueur de grand succ\u00e8s, et nous l&rsquo;utiliserons pour nous propulser vers l&rsquo;avant alors que nous continuons \u00e0 d\u00e9fendre ce secteur vital de notre soci\u00e9t\u00e9<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[63],"tags":[],"post_folder":[],"class_list":["post-19913","post","type-post","status-publish","format-standard","hentry","category-actualites"],"jetpack_featured_media_url":"","acf":[],"_links":{"self":[{"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/posts\/19913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/comments?post=19913"}],"version-history":[{"count":2,"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/posts\/19913\/revisions"}],"predecessor-version":[{"id":19916,"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/posts\/19913\/revisions\/19916"}],"wp:attachment":[{"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/media?parent=19913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/categories?post=19913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/tags?post=19913"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/canadiansciencecentres.ca\/fr\/wp-json\/wp\/v2\/post_folder?post=19913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}